{"id":8044,"date":"2024-11-08T16:32:37","date_gmt":"2024-11-08T14:32:37","guid":{"rendered":"https:\/\/fourthedesign.gr\/en\/?post_type=portfolio&#038;p=8044"},"modified":"2024-11-12T12:20:44","modified_gmt":"2024-11-12T10:20:44","slug":"aluminium-sliding-systems","status":"publish","type":"portfolio","link":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/","title":{"rendered":"Aluminium Sliding Systems"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":8055,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8044","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-3d-modeling","portfolio_category-architecture-visualization","portfolio_category-photorealistic-architectural-renders","portfolio_category-product-design","portfolio_category-visualization"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum<\/title>\n<meta name=\"description\" content=\"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum\" \/>\n<meta property=\"og:description\" content=\"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/\" \/>\n<meta property=\"og:site_name\" content=\"fourthedesign - 3d animation - architecture visualization\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Fourthedesign\/844661815597983\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T10:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2024\/11\/Aluminium-Sliding-Systems-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fourthedesign\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/\",\"url\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/\",\"name\":\"Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Aluminium-Sliding-Systems-1.webp\",\"datePublished\":\"2024-11-08T14:32:37+00:00\",\"dateModified\":\"2024-11-12T10:20:44+00:00\",\"description\":\"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Aluminium-Sliding-Systems-1.webp\",\"contentUrl\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Aluminium-Sliding-Systems-1.webp\",\"width\":960,\"height\":960,\"caption\":\"Aluminium Sliding Systems\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/portfolio\\\/aluminium-sliding-systems\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aluminium Sliding Systems\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/\",\"name\":\"fourthedesign - 3d animation - architecture visualization\",\"description\":\"3d animation architecture visualization interactive apps\",\"publisher\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#organization\",\"name\":\"fourthedesign - Multimedia VR & AR apps - 3d animation - architecture visualization - Real-time Interactivity\",\"url\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/fourthedesign-logo-200_dark1.png\",\"contentUrl\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/fourthedesign-logo-200_dark1.png\",\"width\":200,\"height\":152,\"caption\":\"fourthedesign - Multimedia VR & AR apps - 3d animation - architecture visualization - Real-time Interactivity\"},\"image\":{\"@id\":\"https:\\\/\\\/fourthedesign.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Fourthedesign\\\/844661815597983\",\"https:\\\/\\\/x.com\\\/fourthedesign\",\"https:\\\/\\\/gr.linkedin.com\\\/pub\\\/giannis-kastrinakis\\\/19\\\/a5a\\\/9b7\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fourthedesign\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum","description":"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/","og_locale":"en_US","og_type":"article","og_title":"Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum","og_description":"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency","og_url":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/","og_site_name":"fourthedesign - 3d animation - architecture visualization","article_publisher":"https:\/\/www.facebook.com\/pages\/Fourthedesign\/844661815597983","article_modified_time":"2024-11-12T10:20:44+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2024\/11\/Aluminium-Sliding-Systems-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@fourthedesign","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/","url":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/","name":"Aluminium Sliding Systems - 3D Sliding Solutions in Aluminum","isPartOf":{"@id":"https:\/\/fourthedesign.gr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/#primaryimage"},"image":{"@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/#primaryimage"},"thumbnailUrl":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2024\/11\/Aluminium-Sliding-Systems-1.webp","datePublished":"2024-11-08T14:32:37+00:00","dateModified":"2024-11-12T10:20:44+00:00","description":"Aluminium Sliding Systems - Discover durable 3D aluminum sliding systems for sleek design, enhancing any environment with style and efficiency","breadcrumb":{"@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/#primaryimage","url":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2024\/11\/Aluminium-Sliding-Systems-1.webp","contentUrl":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2024\/11\/Aluminium-Sliding-Systems-1.webp","width":960,"height":960,"caption":"Aluminium Sliding Systems"},{"@type":"BreadcrumbList","@id":"https:\/\/fourthedesign.gr\/en\/portfolio\/aluminium-sliding-systems\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fourthedesign.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Aluminium Sliding Systems"}]},{"@type":"WebSite","@id":"https:\/\/fourthedesign.gr\/en\/#website","url":"https:\/\/fourthedesign.gr\/en\/","name":"fourthedesign - 3d animation - architecture visualization","description":"3d animation architecture visualization interactive apps","publisher":{"@id":"https:\/\/fourthedesign.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fourthedesign.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fourthedesign.gr\/en\/#organization","name":"fourthedesign - Multimedia VR & AR apps - 3d animation - architecture visualization - Real-time Interactivity","url":"https:\/\/fourthedesign.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fourthedesign.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2015\/08\/fourthedesign-logo-200_dark1.png","contentUrl":"https:\/\/fourthedesign.gr\/en\/wp-content\/uploads\/2015\/08\/fourthedesign-logo-200_dark1.png","width":200,"height":152,"caption":"fourthedesign - Multimedia VR & AR apps - 3d animation - architecture visualization - Real-time Interactivity"},"image":{"@id":"https:\/\/fourthedesign.gr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Fourthedesign\/844661815597983","https:\/\/x.com\/fourthedesign","https:\/\/gr.linkedin.com\/pub\/giannis-kastrinakis\/19\/a5a\/9b7","https:\/\/www.youtube.com\/user\/fourthedesign"]}]}},"_links":{"self":[{"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/portfolio\/8044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/comments?post=8044"}],"version-history":[{"count":2,"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/portfolio\/8044\/revisions"}],"predecessor-version":[{"id":8058,"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/portfolio\/8044\/revisions\/8058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/media\/8055"}],"wp:attachment":[{"href":"https:\/\/fourthedesign.gr\/en\/wp-json\/wp\/v2\/media?parent=8044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}